{"id":300830,"date":"2025-03-30T18:34:53","date_gmt":"2025-03-30T10:34:53","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo.webp"},"modified":"2025-03-30T18:35:09","modified_gmt":"2025-03-30T10:35:09","slug":"bali-international-hospital-logo-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/de\/bali-international-hospital-logo-2\/","title":{"rendered":"bali-international-hospital-logo"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-300830","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo.webp\" class=\"attachment-medium size-medium\" alt=\"BIH Logo\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"BIH Logo","media_type":"image","mime_type":"image\/webp","media_details":{"width":300,"height":106,"file":"2025\/03\/bali-international-hospital-logo.webp","filesize":5454,"sizes":{"woocommerce_thumbnail":{"file":"bali-international-hospital-logo-247x106.webp","width":247,"height":106,"filesize":5254,"mime_type":"image\/webp","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo-247x106.webp"},"woocommerce_gallery_thumbnail":{"file":"bali-international-hospital-logo-100x100.webp","width":100,"height":100,"filesize":3450,"mime_type":"image\/webp","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo-100x100.webp"},"cmplz_banner_image":{"file":"bali-international-hospital-logo-300x100.webp","width":300,"height":100,"filesize":5472,"mime_type":"image\/webp","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo-300x100.webp"},"full":{"file":"bali-international-hospital-logo.webp","width":300,"height":106,"mime_type":"image\/webp","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2025\/03\/bali-international-hospital-logo.webp","_links":{"self":[{"href":"https:\/\/bali.com\/de\/wp-json\/wp\/v2\/media\/300830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/de\/wp-json\/wp\/v2\/comments?post=300830"}]}}