{"id":171832,"date":"2023-03-03T13:00:09","date_gmt":"2023-03-03T05:00:09","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png"},"modified":"2023-03-03T13:00:09","modified_gmt":"2023-03-03T05:00:09","slug":"echo-bch-left-2-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/fr\/echo-bch-left-2-2\/","title":{"rendered":"echo-bch-left"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"class_list":["post-171832","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png 600w, https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-510x340.png 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":400,"file":"2023\/03\/echo-bch-left-1.png","filesize":314031,"sizes":{"woocommerce_thumbnail":{"file":"echo-bch-left-1-247x247.png","width":247,"height":247,"filesize":81492,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-247x247.png"},"woocommerce_gallery_thumbnail":{"file":"echo-bch-left-1-100x100.png","width":100,"height":100,"filesize":15319,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-100x100.png"},"woocommerce_single":{"file":"echo-bch-left-1-510x340.png","width":510,"height":340,"filesize":215829,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-510x340.png"},"thumbnail":{"file":"echo-bch-left-1-280x280.png","width":280,"height":280,"filesize":102342,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-280x280.png"},"cmplz_banner_image":{"file":"echo-bch-left-1-350x100.png","width":350,"height":100,"filesize":47068,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1-350x100.png"},"full":{"file":"echo-bch-left-1.png","width":600,"height":400,"mime_type":"image\/png","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/03\/echo-bch-left-1.png","_links":{"self":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/media\/171832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/comments?post=171832"}]}}