{"id":172772,"date":"2023-06-21T14:34:50","date_gmt":"2023-06-21T06:34:50","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg"},"modified":"2023-06-21T14:34:50","modified_gmt":"2023-06-21T06:34:50","slug":"eleven-beach-club-8-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/fr\/eleven-beach-club-8-2\/","title":{"rendered":"eleven-beach-club-8"},"author":8,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-172772","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg 1200w, https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-510x340.jpeg 510w, https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":800,"file":"2023\/06\/eleven-beach-club-8.jpeg","filesize":145513,"sizes":{"woocommerce_thumbnail":{"file":"eleven-beach-club-8-247x247.jpeg","width":247,"height":247,"filesize":20177,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-247x247.jpeg"},"woocommerce_gallery_thumbnail":{"file":"eleven-beach-club-8-100x100.jpeg","width":100,"height":100,"filesize":4735,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-100x100.jpeg"},"woocommerce_single":{"file":"eleven-beach-club-8-510x340.jpeg","width":510,"height":340,"filesize":49010,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-510x340.jpeg"},"thumbnail":{"file":"eleven-beach-club-8-280x280.jpeg","width":280,"height":280,"filesize":24777,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-280x280.jpeg"},"medium_large":{"file":"eleven-beach-club-8-768x512.jpeg","width":768,"height":512,"filesize":92820,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-768x512.jpeg"},"cmplz_banner_image":{"file":"eleven-beach-club-8-350x100.jpeg","width":350,"height":100,"filesize":12950,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8-350x100.jpeg"},"full":{"file":"eleven-beach-club-8.jpeg","width":1200,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/06\/eleven-beach-club-8.jpeg","_links":{"self":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/media\/172772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/fr\/wp-json\/wp\/v2\/comments?post=172772"}]}}