{"id":16841,"date":"2022-02-09T02:46:09","date_gmt":"2022-02-09T02:46:09","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg"},"modified":"2022-02-09T02:46:09","modified_gmt":"2022-02-09T02:46:09","slug":"green-school-bali-600-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/id\/green-school-bali-600-2\/","title":{"rendered":"green school bali 600"},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-16841","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"327\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg 600w, https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-510x278.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":327,"file":"2022\/02\/green-school-bali-600.jpg","filesize":41007,"sizes":{"woocommerce_thumbnail":{"file":"green-school-bali-600-247x247.jpg","width":247,"height":247,"filesize":12394,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-247x247.jpg"},"woocommerce_gallery_thumbnail":{"file":"green-school-bali-600-100x100.jpg","width":100,"height":100,"filesize":3477,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-100x100.jpg"},"woocommerce_single":{"file":"green-school-bali-600-510x278.jpg","width":510,"height":278,"filesize":20791,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-510x278.jpg"},"thumbnail":{"file":"green-school-bali-600-280x280.jpg","width":280,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-280x280.jpg"},"shop_catalog":{"file":"green-school-bali-600-420x280.jpg","width":420,"height":280,"filesize":17649,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-420x280.jpg"},"shop_thumbnail":{"file":"green-school-bali-600-100x100.jpg","width":100,"height":100,"filesize":3477,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600-100x100.jpg"},"full":{"file":"green-school-bali-600.jpg","width":600,"height":327,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/02\/green-school-bali-600.jpg","_links":{"self":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media\/16841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/comments?post=16841"}]}}