{"id":235673,"date":"2023-09-11T11:51:01","date_gmt":"2023-09-11T03:51:01","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg"},"modified":"2023-09-11T11:51:01","modified_gmt":"2023-09-11T03:51:01","slug":"balance-flow-wellness-desa-potato-head-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/id\/balance-flow-wellness-desa-potato-head-2\/","title":{"rendered":"Balance-Flow-Wellness-Desa-Potato-Head"},"author":80,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-235673","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"5464\" height=\"8192\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg 5464w, https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-510x765.jpg 510w, https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-534x800.jpg 534w, https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-768x1151.jpg 768w, https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-1025x1536.jpg 1025w, https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-1366x2048.jpg 1366w\" sizes=\"auto, (max-width: 5464px) 100vw, 5464px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":5464,"height":8192,"file":"2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg","filesize":13930421,"sizes":{"woocommerce_thumbnail":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-247x247.jpg","width":247,"height":247,"filesize":8317,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-247x247.jpg"},"woocommerce_gallery_thumbnail":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-100x100.jpg","width":100,"height":100,"filesize":2355,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-100x100.jpg"},"woocommerce_single":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-510x765.jpg","width":510,"height":765,"filesize":40431,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-510x765.jpg"},"large":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-534x800.jpg","width":534,"height":800,"filesize":44610,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-534x800.jpg"},"thumbnail":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-280x280.jpg","width":280,"height":280,"filesize":10306,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-280x280.jpg"},"medium_large":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-768x1151.jpg","width":768,"height":1151,"filesize":103875,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-768x1151.jpg"},"1536x1536":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-1025x1536.jpg","width":1025,"height":1536,"filesize":204715,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-1025x1536.jpg"},"2048x2048":{"file":"Balance-Flow-Wellness-Desa-Potato-Head-1366x2048.jpg","width":1366,"height":2048,"filesize":388558,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head-1366x2048.jpg"},"full":{"file":"Balance-Flow-Wellness-Desa-Potato-Head.jpg","width":5464,"height":8192,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2023\/09\/Balance-Flow-Wellness-Desa-Potato-Head.jpg","_links":{"self":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media\/235673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/comments?post=235673"}]}}