{"id":24853,"date":"2022-09-08T19:26:40","date_gmt":"2022-09-08T11:26:40","guid":{"rendered":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg"},"modified":"2022-09-08T19:26:40","modified_gmt":"2022-09-08T11:26:40","slug":"anastase-maragos-9dzwzqwzmde-unsplash-2","status":"inherit","type":"attachment","link":"https:\/\/bali.com\/id\/anastase-maragos-9dzwzqwzmde-unsplash-2\/","title":{"rendered":"anastase-maragos-9dzWZQWZMdE-unsplash"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"0","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-24853","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-600x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-600x400.jpg 600w, https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-510x340.jpg 510w, https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-1200x800.jpg 1200w, https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-768x512.jpg 768w, https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg 1500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1000,"file":"2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg","filesize":57844,"sizes":{"woocommerce_thumbnail":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-247x247.jpg","width":247,"height":247,"filesize":5417,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-247x247.jpg"},"woocommerce_gallery_thumbnail":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-100x100.jpg","width":100,"height":100,"filesize":1546,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-100x100.jpg"},"woocommerce_single":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-510x340.jpg","width":510,"height":340,"filesize":10207,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-510x340.jpg"},"medium":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-600x400.jpg","width":600,"height":400,"filesize":13206,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-600x400.jpg"},"large":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-1200x800.jpg","width":1200,"height":800,"filesize":45260,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-1200x800.jpg"},"thumbnail":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-280x280.jpg","width":280,"height":280,"filesize":6733,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-280x280.jpg"},"medium_large":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash-768x512.jpg","width":768,"height":512,"filesize":20604,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash-768x512.jpg"},"full":{"file":"anastase-maragos-9dzWZQWZMdE-unsplash.jpg","width":1500,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bali.com\/wp-content\/uploads\/2022\/09\/anastase-maragos-9dzWZQWZMdE-unsplash.jpg","_links":{"self":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media\/24853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bali.com\/id\/wp-json\/wp\/v2\/comments?post=24853"}]}}